{"id":617,"count":1,"description":"","link":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/","name":"film","slug":"film","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>film Archives : Keith Ikeda-Barry<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"film Archives : Keith Ikeda-Barry\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/\" \/>\n<meta property=\"og:site_name\" content=\"Keith Ikeda-Barry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/\",\"url\":\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/\",\"name\":\"film Archives : Keith Ikeda-Barry\",\"isPartOf\":{\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ikedabarry.com\/blogK\/tag\/film\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ikedabarry.com\/blogK\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"film\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#website\",\"url\":\"https:\/\/ikedabarry.com\/blogK\/\",\"name\":\"Keith Ikeda-Barry\",\"description\":\"Portfolio\",\"publisher\":{\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/b8c37c6ca5a649332657d47499db20ee\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ikedabarry.com\/blogK\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/b8c37c6ca5a649332657d47499db20ee\",\"name\":\"Keith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d5f08d970c6b93020999736ec763214?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d5f08d970c6b93020999736ec763214?s=96&r=g\",\"caption\":\"Keith\"},\"logo\":{\"@id\":\"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"film Archives : Keith Ikeda-Barry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/","og_locale":"en_US","og_type":"article","og_title":"film Archives : Keith Ikeda-Barry","og_url":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/","og_site_name":"Keith Ikeda-Barry","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/","url":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/","name":"film Archives : Keith Ikeda-Barry","isPartOf":{"@id":"https:\/\/ikedabarry.com\/blogK\/#website"},"breadcrumb":{"@id":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ikedabarry.com\/blogK\/tag\/film\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ikedabarry.com\/blogK\/"},{"@type":"ListItem","position":2,"name":"film"}]},{"@type":"WebSite","@id":"https:\/\/ikedabarry.com\/blogK\/#website","url":"https:\/\/ikedabarry.com\/blogK\/","name":"Keith Ikeda-Barry","description":"Portfolio","publisher":{"@id":"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/b8c37c6ca5a649332657d47499db20ee"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikedabarry.com\/blogK\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/b8c37c6ca5a649332657d47499db20ee","name":"Keith","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7d5f08d970c6b93020999736ec763214?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d5f08d970c6b93020999736ec763214?s=96&r=g","caption":"Keith"},"logo":{"@id":"https:\/\/ikedabarry.com\/blogK\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ikedabarry.com\/blogK\/wp-json\/wp\/v2\/tags\/617"}],"collection":[{"href":"https:\/\/ikedabarry.com\/blogK\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ikedabarry.com\/blogK\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ikedabarry.com\/blogK\/wp-json\/wp\/v2\/posts?tags=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}